{"id":177262,"date":"2012-07-16T00:00:00","date_gmt":"2012-07-15T22:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/symbool-black-triangle-bij-de-specialiteiten-met-een-nieuw-actief-bestanddeel-lijst-van-de-geneesmiddelen-juni-2012\/"},"modified":"2026-05-07T19:13:47","modified_gmt":"2026-05-07T17:13:47","slug":"symbool-black-triangle-bij-de-specialiteiten-met-een-nieuw-actief-bestanddeel-lijst-van-de-geneesmiddelen-juni-2012","status":"publish","type":"post","link":"https:\/\/bcfi.be\/nl\/symbool-black-triangle-bij-de-specialiteiten-met-een-nieuw-actief-bestanddeel-lijst-van-de-geneesmiddelen-juni-2012\/","title":{"rendered":"Symbool &#8216;black triangle&#8217;\u00a0bij de specialiteiten met een nieuw actief bestanddeel: lijst van de geneesmiddelen\u00a0juni 2012"},"content":{"rendered":"<div class='tekst'>\n<p><span style='font-size:11px'>\u00a0<\/span><span style='font-size:11px'>Om meer aandacht te vestigen op de specialiteiten met een nieuw actief bestanddeel wordt\u00a0in het Gecommentarieerd Geneesmiddelenrepertorium bij deze specialiteiten het symbool \u00a0<img alt='' src='https:\/\/www.bcfi.be\/IMAGES\/SURV.GIF' style='height:10px; width:10px' \/>\u00a0getoond gedurende de eerste drie jaar na commercialisering [<a href='https:\/\/www.bcfi.be\/Folia\/2007\/F34N12G.cfm' target='_blank'>zie Folia december 2007<\/a>]. Met dit symbool wil het Centrum voor Geneesmiddelenbewaking van het Federaal Agentschap voor Geneesmiddelen en Gezondheidsproducten (FAGG) artsen en apothekers oproepen om vermoedens van ongewenste effecten voor deze middelen zeker te rapporteren&#x002C; zelfs bij twijfel over een causaal verband.<\/span><\/p>\n<p><span style='font-size:11px'>\u00a0<\/span><\/p>\n<p><span style='font-size:11px'>De lijst van de geneesmiddelen met symbool \u00a0<img alt='' src='https:\/\/www.bcfi.be\/IMAGES\/SURV.GIF' style='height:10px; width:10px' \/>\u00a0in het Repertorium\u00a0juni 2012&#x002C; is\u00a0te consulteren via volgende link: <a href='\/userfiles\/File\/Med-black-triangle-NL-07072012.pdf'>Lijst van de nieuwe geneesmiddelen met symbool<\/a>\u00a0<img alt='' src='https:\/\/www.bcfi.be\/IMAGES\/SURV.GIF' style='height:10px; width:10px' \/><\/span><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Om meer aandacht te vestigen op de specialiteiten met een  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43,182],"tags":[20213,20224],"class_list":["post-177262","post","type-post","status-publish","format-standard","hentry","category-nieuw","category-2012-nl","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/bcfi.be\/nl\/wp-json\/wp\/v2\/posts\/177262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bcfi.be\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bcfi.be\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bcfi.be\/nl\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/bcfi.be\/nl\/wp-json\/wp\/v2\/comments?post=177262"}],"version-history":[{"count":1,"href":"https:\/\/bcfi.be\/nl\/wp-json\/wp\/v2\/posts\/177262\/revisions"}],"predecessor-version":[{"id":179836,"href":"https:\/\/bcfi.be\/nl\/wp-json\/wp\/v2\/posts\/177262\/revisions\/179836"}],"wp:attachment":[{"href":"https:\/\/bcfi.be\/nl\/wp-json\/wp\/v2\/media?parent=177262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bcfi.be\/nl\/wp-json\/wp\/v2\/categories?post=177262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bcfi.be\/nl\/wp-json\/wp\/v2\/tags?post=177262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}